{"id":4721,"date":"2021-03-15T20:39:36","date_gmt":"2021-03-15T19:39:36","guid":{"rendered":"https:\/\/somosdelprieto.com\/?p=4721"},"modified":"2021-03-18T14:14:53","modified_gmt":"2021-03-18T13:14:53","slug":"telereto-de-innovaciony-creatividad-de-la-fundacion-princesa-de-girona-nuestro-centro-acapara-la-segunda-fase-en-castilla-la-mancha","status":"publish","type":"post","link":"https:\/\/somosdelprieto.com\/index.php\/2021\/03\/15\/telereto-de-innovaciony-creatividad-de-la-fundacion-princesa-de-girona-nuestro-centro-acapara-la-segunda-fase-en-castilla-la-mancha\/","title":{"rendered":"TELERETO DE INNOVACI\u00d3N Y CREATIVIDAD DE LA FUNDACI\u00d3N PRINCESA DE GIRONA: NUESTRO CENTRO ACAPARA LA SEGUNDA FASE EN CASTILLA LA MANCHA"},"content":{"rendered":"\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"IES GREGORIO PRIETO V2\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/vPP6SyDNvvQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Princesa de Girona, con la finalidad de fomentar la competencia emprendedora, ha lanzado un telereto de innovaci\u00f3n y creatividad para el alumnado de Castilla-La Mancha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante cuatro semanas, estudiantes&nbsp;de nuestra regi\u00f3n han trabajado en equipo&nbsp;de forma virtual para encontrar soluciones disruptivas y originales al siguiente Telereto:&nbsp;\u00abNueva visi\u00f3n y misi\u00f3n empresarial: creatividad, proactividad y anticipaci\u00f3n\u00bb. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este proceso, han estado guiados por el emprendedor&nbsp;Xavier Verdaguer,  adoptando metodolog\u00edas que usan las start-ups de \u00e9xito, que han fomentado su imaginaci\u00f3n y sus capacidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pues bien,  de los cuatro equipos de Castilla-La Mancha que han accedido a la segunda fase, dos son de nuestro centro. Concretamente se trata de dos equipos de 1\u00ba curso del ciclo formativo de grado superior \u00abAdministraci\u00f3n y Finanzas\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pr\u00f3ximo mi\u00e9rcoles 17 de marzo, ambos equipos defender\u00e1n sus innovadoras propuestas (obtenidas a trav\u00e9s del m\u00e9todo Lombard) en un acto que se celebrar\u00e1 en la Real Fundaci\u00f3n de Toledo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los alumnos\/as que han conseguido llegar a esta fase son:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-JAVIER GARCIA GARCIA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-VIVIANA ALEXANDRA HERRERA TORRES<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-JAIME RAMIRO GALARZA VAZQUEZ<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-JESUS JIMENEZ VILLAHERMOSA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-FATIMA PERALTA GOMEZ<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-MERCEDES SEGOVIA RAMIREZ<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-LETICIA TOLEDO SANCHEZ<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>De esta fase solo dos equipos pasar\u00e1n&nbsp;a la final nacional, donde competir\u00e1n&nbsp;con los ganadores de otras comunidades aut\u00f3nomas. Independientemente&nbsp;del resultado, poder realizar una presentaci\u00f3n&nbsp;ante tan distinguido p\u00fablico supone un aliciente y marca un hito en su formaci\u00f3n&nbsp;dentro del m\u00f3dulo profesional \u00abComunicaci\u00f3n y Atenci\u00f3n al Cliente\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el centro queremos felicitar al profesor Daniel Pel\u00e1ez Ord\u00f3\u00f1ez, gran responsable de que estos alumnos hayan llegado tan lejos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/somosdelprieto.com\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-15-at-20.16.14-1024x768.jpeg\" alt=\"\" class=\"wp-image-4730\" srcset=\"https:\/\/somosdelprieto.com\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-15-at-20.16.14-1024x768.jpeg 1024w, https:\/\/somosdelprieto.com\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-15-at-20.16.14-300x225.jpeg 300w, https:\/\/somosdelprieto.com\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-15-at-20.16.14-768x576.jpeg 768w, https:\/\/somosdelprieto.com\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-15-at-20.16.14-1536x1152.jpeg 1536w, https:\/\/somosdelprieto.com\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-15-at-20.16.14.jpeg 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.elecodevaldepenas.es\/texto-diario\/mostrar\/2796019\/ies-gregorio-prieto-final-reto-emprendedor-fundacion-princesa-girona-entrega-miercoles-premios-toledo-presencia-reina-letizia\" target=\"_blank\">Ver noticia en ECOVALDEPE\u00d1AS<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n Princesa de Girona, con la finalidad de fomentar la competencia emprendedora, ha lanzado un telereto de innovaci\u00f3n y creatividad para el alumnado de Castilla-La Mancha. Durante cuatro semanas, estudiantes&nbsp;de nuestra regi\u00f3n han trabajado en equipo&nbsp;de forma virtual para encontrar soluciones disruptivas y originales al siguiente Telereto:&nbsp;\u00abNueva visi\u00f3n y misi\u00f3n empresarial: creatividad, proactividad y &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/somosdelprieto.com\/index.php\/2021\/03\/15\/telereto-de-innovaciony-creatividad-de-la-fundacion-princesa-de-girona-nuestro-centro-acapara-la-segunda-fase-en-castilla-la-mancha\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abTELERETO DE INNOVACI\u00d3N Y CREATIVIDAD DE LA FUNDACI\u00d3N PRINCESA DE GIRONA: NUESTRO CENTRO ACAPARA LA SEGUNDA FASE EN CASTILLA LA MANCHA\u00bb<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":4722,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,62,1,14],"tags":[108],"class_list":["post-4721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administracion","category-innovacion","category-noticias","category-premios","tag-innovacion"],"_links":{"self":[{"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/posts\/4721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/comments?post=4721"}],"version-history":[{"count":5,"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/posts\/4721\/revisions"}],"predecessor-version":[{"id":4770,"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/posts\/4721\/revisions\/4770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/media\/4722"}],"wp:attachment":[{"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/media?parent=4721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/categories?post=4721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/somosdelprieto.com\/index.php\/wp-json\/wp\/v2\/tags?post=4721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}